{"id":8154,"date":"2026-09-01T13:04:37","date_gmt":"2026-09-01T19:04:37","guid":{"rendered":"https:\/\/centroculturalteopanzolco.com\/?p=8154"},"modified":"2026-09-01T13:04:37","modified_gmt":"2026-09-01T19:04:37","slug":"rosa-de-dos-aromas","status":"publish","type":"post","link":"https:\/\/centroculturalteopanzolco.com\/en\/2026\/09\/01\/rosa-de-dos-aromas\/","title":{"rendered":"Rosa de dos aromas"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Obra de teatro del g\u00e9nero comedia interpretada por dos actrices. Duraci\u00f3n aproximada de 90 minutos sin intermedio. Rosa de dos aromas es una comedia \u00e1gil y astuta que combina humor y melodrama para explorar las contradicciones del amor rom\u00e1ntico y las segundas oportunidades. La pieza sigue a personajes cotidianos enfrentando deseos, enga\u00f1os y expectativas sociales, y lo hace con di\u00e1logos chispeantes, situaciones bien construidas y giros que mantienen el inter\u00e9s sin perder la calidez humana.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Participan: Itati Cantoral y Marlen Fabela<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Boletos a la venta en <\/span><a href=\"https:\/\/soldout.ticketcity.mx\/rosa-de-dos-aromas-cuernavaca\/centro-cultural-teopanzolco\/2026\/10\/21\"><span style=\"font-weight: 400;\">Ticket City<\/span><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Obra de teatro del g\u00e9nero comedia interpretada por dos actrices. Duraci\u00f3n aproximada de 90 minutos sin intermedio. Rosa de dos aromas es una comedia \u00e1gil y astuta que combina humor y melodrama para explorar las contradicciones del amor rom\u00e1ntico y las segundas oportunidades. La pieza sigue a personajes cotidianos enfrentando deseos, enga\u00f1os y expectativas sociales, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":8156,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[1,48],"tags":[],"class_list":["post-8154","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cartelera","category-teatro"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rosa de dos aromas - Centro Cultural Teopanzolco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/centroculturalteopanzolco.com\/en\/2026\/09\/01\/rosa-de-dos-aromas\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rosa de dos aromas - Centro Cultural Teopanzolco\" \/>\n<meta property=\"og:description\" content=\"Obra de teatro del g\u00e9nero comedia interpretada por dos actrices. Duraci\u00f3n aproximada de 90 minutos sin intermedio. Rosa de dos aromas es una comedia \u00e1gil y astuta que combina humor y melodrama para explorar las contradicciones del amor rom\u00e1ntico y las segundas oportunidades. La pieza sigue a personajes cotidianos enfrentando deseos, enga\u00f1os y expectativas sociales, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/centroculturalteopanzolco.com\/en\/2026\/09\/01\/rosa-de-dos-aromas\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro Cultural Teopanzolco\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CCTeopanzolco\" \/>\n<meta property=\"article:published_time\" content=\"2026-09-01T19:04:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/centroculturalteopanzolco.com\/wp-content\/uploads\/2026\/09\/rosadedosaromas-03.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1042\" \/>\n\t<meta property=\"og:image:height\" content=\"1042\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CCTeopanzolco\" \/>\n<meta name=\"twitter:site\" content=\"@CCTeopanzolco\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/centroculturalteopanzolco.com\\\/2026\\\/09\\\/01\\\/rosa-de-dos-aromas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centroculturalteopanzolco.com\\\/2026\\\/09\\\/01\\\/rosa-de-dos-aromas\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/centroculturalteopanzolco.com\\\/#\\\/schema\\\/person\\\/29b5e107c7a621c3f99f99ba274ad8e8\"},\"headline\":\"Rosa de dos aromas\",\"datePublished\":\"2026-09-01T19:04:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/centroculturalteopanzolco.com\\\/2026\\\/09\\\/01\\\/rosa-de-dos-aromas\\\/\"},\"wordCount\":97,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/centroculturalteopanzolco.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/centroculturalteopanzolco.com\\\/2026\\\/09\\\/01\\\/rosa-de-dos-aromas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centroculturalteopanzolco.com\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/rosadedosaromas-03.webp\",\"articleSection\":[\"Cartelera\",\"Teatro\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/centroculturalteopanzolco.com\\\/2026\\\/09\\\/01\\\/rosa-de-dos-aromas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/centroculturalteopanzolco.com\\\/2026\\\/09\\\/01\\\/rosa-de-dos-aromas\\\/\",\"url\":\"https:\\\/\\\/centroculturalteopanzolco.com\\\/2026\\\/09\\\/01\\\/rosa-de-dos-aromas\\\/\",\"name\":\"Rosa de dos aromas - Centro Cultural Teopanzolco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centroculturalteopanzolco.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/centroculturalteopanzolco.com\\\/2026\\\/09\\\/01\\\/rosa-de-dos-aromas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/centroculturalteopanzolco.com\\\/2026\\\/09\\\/01\\\/rosa-de-dos-aromas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centroculturalteopanzolco.com\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/rosadedosaromas-03.webp\",\"datePublished\":\"2026-09-01T19:04:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/centroculturalteopanzolco.com\\\/2026\\\/09\\\/01\\\/rosa-de-dos-aromas\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/centroculturalteopanzolco.com\\\/2026\\\/09\\\/01\\\/rosa-de-dos-aromas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/centroculturalteopanzolco.com\\\/2026\\\/09\\\/01\\\/rosa-de-dos-aromas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/centroculturalteopanzolco.com\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/rosadedosaromas-03.webp\",\"contentUrl\":\"https:\\\/\\\/centroculturalteopanzolco.com\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/rosadedosaromas-03.webp\",\"width\":1042,\"height\":1042},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/centroculturalteopanzolco.com\\\/2026\\\/09\\\/01\\\/rosa-de-dos-aromas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/centroculturalteopanzolco.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rosa de dos aromas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/centroculturalteopanzolco.com\\\/#website\",\"url\":\"https:\\\/\\\/centroculturalteopanzolco.com\\\/\",\"name\":\"Centro Cultural Teopanzolco\",\"description\":\"Un espacio para el arte y la cultura en Morelos\",\"publisher\":{\"@id\":\"https:\\\/\\\/centroculturalteopanzolco.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/centroculturalteopanzolco.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/centroculturalteopanzolco.com\\\/#organization\",\"name\":\"Centro Cultural Teopanzolco\",\"url\":\"https:\\\/\\\/centroculturalteopanzolco.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/centroculturalteopanzolco.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/centroculturalteopanzolco.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Logo-de-Secretaria-de-cultura-y-Logo-Centro-Cultural-de-Teopanzolco.png\",\"contentUrl\":\"https:\\\/\\\/centroculturalteopanzolco.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Logo-de-Secretaria-de-cultura-y-Logo-Centro-Cultural-de-Teopanzolco.png\",\"width\":618,\"height\":89,\"caption\":\"Centro Cultural Teopanzolco\"},\"image\":{\"@id\":\"https:\\\/\\\/centroculturalteopanzolco.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CCTeopanzolco\",\"https:\\\/\\\/x.com\\\/CCTeopanzolco\",\"https:\\\/\\\/www.instagram.com\\\/ccteopanzolco\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/centroculturalteopanzolco.com\\\/#\\\/schema\\\/person\\\/29b5e107c7a621c3f99f99ba274ad8e8\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23d0c7d35785ab1fc46bbd4955d0d0bf759bd594cac4248050c0880c158ec2ac?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23d0c7d35785ab1fc46bbd4955d0d0bf759bd594cac4248050c0880c158ec2ac?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23d0c7d35785ab1fc46bbd4955d0d0bf759bd594cac4248050c0880c158ec2ac?s=96&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/centroculturalteopanzolco.com\\\/en\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rosa de dos aromas - Centro Cultural Teopanzolco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/centroculturalteopanzolco.com\/en\/2026\/09\/01\/rosa-de-dos-aromas\/","og_locale":"en_US","og_type":"article","og_title":"Rosa de dos aromas - Centro Cultural Teopanzolco","og_description":"Obra de teatro del g\u00e9nero comedia interpretada por dos actrices. Duraci\u00f3n aproximada de 90 minutos sin intermedio. Rosa de dos aromas es una comedia \u00e1gil y astuta que combina humor y melodrama para explorar las contradicciones del amor rom\u00e1ntico y las segundas oportunidades. La pieza sigue a personajes cotidianos enfrentando deseos, enga\u00f1os y expectativas sociales, [&hellip;]","og_url":"https:\/\/centroculturalteopanzolco.com\/en\/2026\/09\/01\/rosa-de-dos-aromas\/","og_site_name":"Centro Cultural Teopanzolco","article_publisher":"https:\/\/www.facebook.com\/CCTeopanzolco","article_published_time":"2026-09-01T19:04:37+00:00","og_image":[{"width":1042,"height":1042,"url":"https:\/\/centroculturalteopanzolco.com\/wp-content\/uploads\/2026\/09\/rosadedosaromas-03.webp","type":"image\/webp"}],"author":"admin","twitter_card":"summary_large_image","twitter_creator":"@CCTeopanzolco","twitter_site":"@CCTeopanzolco","twitter_misc":{"Written by":"admin","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/centroculturalteopanzolco.com\/2026\/09\/01\/rosa-de-dos-aromas\/#article","isPartOf":{"@id":"https:\/\/centroculturalteopanzolco.com\/2026\/09\/01\/rosa-de-dos-aromas\/"},"author":{"name":"admin","@id":"https:\/\/centroculturalteopanzolco.com\/#\/schema\/person\/29b5e107c7a621c3f99f99ba274ad8e8"},"headline":"Rosa de dos aromas","datePublished":"2026-09-01T19:04:37+00:00","mainEntityOfPage":{"@id":"https:\/\/centroculturalteopanzolco.com\/2026\/09\/01\/rosa-de-dos-aromas\/"},"wordCount":97,"commentCount":0,"publisher":{"@id":"https:\/\/centroculturalteopanzolco.com\/#organization"},"image":{"@id":"https:\/\/centroculturalteopanzolco.com\/2026\/09\/01\/rosa-de-dos-aromas\/#primaryimage"},"thumbnailUrl":"https:\/\/centroculturalteopanzolco.com\/wp-content\/uploads\/2026\/09\/rosadedosaromas-03.webp","articleSection":["Cartelera","Teatro"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/centroculturalteopanzolco.com\/2026\/09\/01\/rosa-de-dos-aromas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/centroculturalteopanzolco.com\/2026\/09\/01\/rosa-de-dos-aromas\/","url":"https:\/\/centroculturalteopanzolco.com\/2026\/09\/01\/rosa-de-dos-aromas\/","name":"Rosa de dos aromas - Centro Cultural Teopanzolco","isPartOf":{"@id":"https:\/\/centroculturalteopanzolco.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/centroculturalteopanzolco.com\/2026\/09\/01\/rosa-de-dos-aromas\/#primaryimage"},"image":{"@id":"https:\/\/centroculturalteopanzolco.com\/2026\/09\/01\/rosa-de-dos-aromas\/#primaryimage"},"thumbnailUrl":"https:\/\/centroculturalteopanzolco.com\/wp-content\/uploads\/2026\/09\/rosadedosaromas-03.webp","datePublished":"2026-09-01T19:04:37+00:00","breadcrumb":{"@id":"https:\/\/centroculturalteopanzolco.com\/2026\/09\/01\/rosa-de-dos-aromas\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/centroculturalteopanzolco.com\/2026\/09\/01\/rosa-de-dos-aromas\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/centroculturalteopanzolco.com\/2026\/09\/01\/rosa-de-dos-aromas\/#primaryimage","url":"https:\/\/centroculturalteopanzolco.com\/wp-content\/uploads\/2026\/09\/rosadedosaromas-03.webp","contentUrl":"https:\/\/centroculturalteopanzolco.com\/wp-content\/uploads\/2026\/09\/rosadedosaromas-03.webp","width":1042,"height":1042},{"@type":"BreadcrumbList","@id":"https:\/\/centroculturalteopanzolco.com\/2026\/09\/01\/rosa-de-dos-aromas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/centroculturalteopanzolco.com\/"},{"@type":"ListItem","position":2,"name":"Rosa de dos aromas"}]},{"@type":"WebSite","@id":"https:\/\/centroculturalteopanzolco.com\/#website","url":"https:\/\/centroculturalteopanzolco.com\/","name":"Cultural Center Teopanzolco","description":"A space for art and culture in Morelos","publisher":{"@id":"https:\/\/centroculturalteopanzolco.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/centroculturalteopanzolco.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/centroculturalteopanzolco.com\/#organization","name":"Cultural Center Teopanzolco","url":"https:\/\/centroculturalteopanzolco.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/centroculturalteopanzolco.com\/#\/schema\/logo\/image\/","url":"https:\/\/centroculturalteopanzolco.com\/wp-content\/uploads\/2024\/11\/Logo-de-Secretaria-de-cultura-y-Logo-Centro-Cultural-de-Teopanzolco.png","contentUrl":"https:\/\/centroculturalteopanzolco.com\/wp-content\/uploads\/2024\/11\/Logo-de-Secretaria-de-cultura-y-Logo-Centro-Cultural-de-Teopanzolco.png","width":618,"height":89,"caption":"Centro Cultural Teopanzolco"},"image":{"@id":"https:\/\/centroculturalteopanzolco.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CCTeopanzolco","https:\/\/x.com\/CCTeopanzolco","https:\/\/www.instagram.com\/ccteopanzolco\/"]},{"@type":"Person","@id":"https:\/\/centroculturalteopanzolco.com\/#\/schema\/person\/29b5e107c7a621c3f99f99ba274ad8e8","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/23d0c7d35785ab1fc46bbd4955d0d0bf759bd594cac4248050c0880c158ec2ac?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/23d0c7d35785ab1fc46bbd4955d0d0bf759bd594cac4248050c0880c158ec2ac?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/23d0c7d35785ab1fc46bbd4955d0d0bf759bd594cac4248050c0880c158ec2ac?s=96&r=g","caption":"admin"},"url":"https:\/\/centroculturalteopanzolco.com\/en\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/centroculturalteopanzolco.com\/en\/wp-json\/wp\/v2\/posts\/8154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/centroculturalteopanzolco.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/centroculturalteopanzolco.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/centroculturalteopanzolco.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/centroculturalteopanzolco.com\/en\/wp-json\/wp\/v2\/comments?post=8154"}],"version-history":[{"count":1,"href":"https:\/\/centroculturalteopanzolco.com\/en\/wp-json\/wp\/v2\/posts\/8154\/revisions"}],"predecessor-version":[{"id":8157,"href":"https:\/\/centroculturalteopanzolco.com\/en\/wp-json\/wp\/v2\/posts\/8154\/revisions\/8157"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/centroculturalteopanzolco.com\/en\/wp-json\/wp\/v2\/media\/8156"}],"wp:attachment":[{"href":"https:\/\/centroculturalteopanzolco.com\/en\/wp-json\/wp\/v2\/media?parent=8154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/centroculturalteopanzolco.com\/en\/wp-json\/wp\/v2\/categories?post=8154"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/centroculturalteopanzolco.com\/en\/wp-json\/wp\/v2\/tags?post=8154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}